{"id":23,"count":8,"description":"","link":"http:\/\/www.julienrossi.com\/blog\/tag\/relations-internationales\/","name":"relations internationales","slug":"relations-internationales","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"http:\/\/www.julienrossi.com\/blog\/wp-json\/wp\/v2\/tags\/23","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.julienrossi.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"http:\/\/www.julienrossi.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"http:\/\/www.julienrossi.com\/blog\/wp-json\/wp\/v2\/posts?tags=23"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}